{"id":23486,"date":"2025-04-13T17:39:50","date_gmt":"2025-04-13T17:39:50","guid":{"rendered":"https:\/\/primegloballab.com\/?post_type=product&#038;p=23486"},"modified":"2025-12-10T12:48:34","modified_gmt":"2025-12-10T12:48:34","slug":"5-meo-dipt-hydrochlorid","status":"publish","type":"product","link":"https:\/\/primegloballab.com\/de\/geschaft\/5-mai-einbruch\/5-meo-dipt-hydrochlorid\/","title":{"rendered":"5-MeO-DiPT hydrochloride"},"content":{"rendered":"<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5-MeO-DiPT Hydrochloride \u2013 Product Description, Uses, Benefits &amp; Disadvantages &amp; FAQs<\/span><\/span><\/strong><\/h3>\n<h4><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Beschreibung des Produkts<\/span><\/span><\/strong><\/h4>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5-MeO-DiPT (5-Methoxy-N,N-diisopropyltryptamine) hydrochloride is a research chemical belonging to the tryptamine class. Also known as\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">&#8220;Foxy Methoxy&#8221;<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0in non-scientific literature, it has a unique psychoactive profile, making it of interest for pharmacological research. This product is sold exclusively for\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">scientific purposes<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0and is\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">not intended for human consumption<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> .<\/span><\/span><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Chemical name:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a05-Methoxy-N,N-diisopropyltryptamine hydrochloride<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formel:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0C\u2081\u2087H\u2082\u2086N\u2082O \u00b7 HCl<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Molecular mass:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0310.86 g\/mol<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Reinheit:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0\u226598% (verified by HPLC)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Form:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0White crystalline powder<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Solubility:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Soluble in water and ethanol<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<hr \/>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Use Cases (Research Purposes)<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5-MeO-DiPT HCl is being investigated in scientific settings because of:<\/span><\/span><\/p>\n<ol start=\"1\">\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Serotonergic activity:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Study of interactions with 5-HT\u2081A and 5-HT\u2082A receptors.<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Sensory modulation:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Investigating auditory and tactile effects in preclinical models.<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Comparative pharmacology:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Analysis of differences with related substances such as DMT and 5-MeO-DMT.<\/span><\/span><\/p>\n<\/li>\n<\/ol>\n<hr \/>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Recommended Dosage (For Research)<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><em><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Please note: This product is not for human use. Dosages are based on theoretical research.<\/span><\/span><\/em><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Low dose:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a04-8 mg (mild sensory effects)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Average dose:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a08-12 mg (marked auditory and tactile changes)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">High dose:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a012-20 mg (intense effects, for experienced researchers only)<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Method of administration:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Oral (in solution):<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Use demineralized water or ethanol as a solvent.<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Intranasal (theoretical):<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Must be dosed carefully due to possible irritation.<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Vaporization (theoretical):<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0May require conversion to a free base.<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<hr \/>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Disadvantages &amp; Risks<\/span><\/span><\/strong><\/h3>\n<ol start=\"1\">\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Unpredictable effects:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0May cause strong auditory hallucinations and body sensations.<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Possible side effects:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Nausea (in some preclinical studies)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Increased blood pressure and heart rate<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Anxiety or confusion at higher doses<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Limited toxicity data:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Little is known about long-term effects.<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Legality:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0In many countries, including the Netherlands, it falls under the\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Opium Act<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0and is\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">not legal for recreational use<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> .<\/span><\/span><\/p>\n<\/li>\n<\/ol>\n<hr \/>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Frequently Asked Questions (FAQs)<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1. Is 5-MeO-DiPT legal in the Netherlands?<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">It falls under the\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Opium Act<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0and is only permitted for\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">wissenschaftliche Forschung<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> .<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2. What are the most important effects in research?<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Auditory enhancement<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0and\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">tactile sensations<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0have been frequently reported in preclinical models.<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">3. Can I receive a lab report (COA)?<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Yes, each batch comes with a\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Analysezertifikat (HPLC\/GC-MS)<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> .<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4. How should I store this product?<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Store in an\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">airtight container<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> ,\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">cool (below 25\u00b0C)<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0and\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">protected from light<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> .<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5. Is 5-MeO-DiPT suitable for beginners in research?<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">No<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> , due to its potency and potential intense effects it is only recommended for\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">experienced researchers<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> .<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<hr \/>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Conclusion<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5-MeO-DiPT hydrochloride is a powerful research chemical with unique effects on sensory perception. Due to its strong and sometimes unpredictable effects, it should\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">only be used in controlled laboratory conditions<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0.<\/span><\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><em><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Disclaimer: This product is intended for scientific research only and is not for human consumption. The buyer is responsible for compliance with local laws.<\/span><\/span><\/em><\/p>\n<hr \/>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Questions?<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Contact our scientific support team for more information about safe use and analytical data.<\/span><\/span><\/p>","protected":false},"excerpt":{"rendered":"<h3><span data-sheets-value=\"{\" data-sheets-userformat=\"{\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5-MeO-DiPT hydrochloride properties<\/span><\/span><\/span><\/span><\/span><\/h3>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Synonym:<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 5-methoxy-N,N-diisopropyltryptamine hydrochloride <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">CAS Number:<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> n\/a <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formula:<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 3-[2-(diisopropyl)ethyl]-5-methoxyindole hydrochloride <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Molar mass:<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 310.9 g\/mol <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Purity:<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> &gt;97%<\/span><\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":28977,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[82],"product_cat":[487,381],"product_tag":[326],"class_list":{"0":"post-23486","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-research-chemical","7":"product_cat-5-meo-dipt","8":"product_cat-tryptamines","9":"product_tag-nl","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/product\/23486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/comments?post=23486"}],"version-history":[{"count":5,"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/product\/23486\/revisions"}],"predecessor-version":[{"id":28074,"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/product\/23486\/revisions\/28074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/media\/28977"}],"wp:attachment":[{"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/media?parent=23486"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/product_brand?post=23486"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/product_cat?post=23486"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/primegloballab.com\/de\/wp-json\/wp\/v2\/product_tag?post=23486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}