{"id":23689,"date":"2025-04-13T17:40:15","date_gmt":"2025-04-13T17:40:15","guid":{"rendered":"https:\/\/primegloballab.com\/?post_type=product&#038;p=23689"},"modified":"2025-12-10T11:41:29","modified_gmt":"2025-12-10T11:41:29","slug":"3fa-kopen","status":"publish","type":"product","link":"https:\/\/primegloballab.com\/nl\/winkelen\/3-fa\/3fa-kopen\/","title":{"rendered":"3-FA (3-fluoramfetamine)"},"content":{"rendered":"<h1><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Buy 3fa (3-Fluoroamphetamine) \u2013 Detailed Product Description for Scientific Research<\/span><\/span><\/h1>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Inleiding<\/span><\/span><\/h2>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Buy 3fa, 3-Fluoroamphetamine (3-FA) is a research chemical of the phenethylamine class, characterized by a fluorine atom at the 3-position of the aromatic ring. The substance is used exclusively in controlled research environments for pharmacological and neurochemical research. This product description provides detailed information on its chemical properties, applications, and safety precautions.<\/span><\/span><\/p>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Chemische eigenschappen<\/span><\/span><\/h2>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Systematic name: 1-(3-fluorophenyl)-2-aminopropane<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Molecular formula: C\u2089H\u2081\u2082FN<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Molecular mass: 153.20 g\/mol<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Purity: \u226598% (HPLC and GC-MS)<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Appearance: White to light beige crystalline powder<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Melting point: 180\u2013185\u00b0C (with decomposition)<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Solubility: Sparingly soluble in water, freely soluble in ethanol and methanol<\/span><\/span><\/li>\n<\/ul>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Stability and Storage<\/span><\/span><\/h2>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Storage conditions: 2\u20138\u00b0C in airtight, light-proof packaging<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Shelf life: 24 months when stored correctly<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Sensitivity: Light-sensitive and hygroscopic<\/span><\/span><\/li>\n<\/ul>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Potential Research Applications<\/span><\/span><\/h2>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">3-FA is being investigated for:<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Interaction with dopaminergic and noradrenergic transporters<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Comparative pharmacology of amphetamine derivatives<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Analysis of neurotransmitter release mechanisms<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Behavioral studies in preclinical models<\/span><\/span><\/li>\n<\/ul>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Please note: Only intended for in vitro and non-clinical animal research within legal frameworks.<\/span><\/span><\/p>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Veiligheidsprotocol<\/span><\/span><\/h2>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Personal Protection<\/span><\/span><\/h3>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Nitrile gloves<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Long-sleeved lab coat<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Veiligheidsbril<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">FFP2 mask when handling the powder<\/span><\/span><\/li>\n<\/ul>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Working conditions<\/span><\/span><\/h3>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Handle only under fume hood<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Prevent dust formation<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Use of explosion-proof equipment required<\/span><\/span><\/li>\n<\/ul>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">First aid<\/span><\/span><\/h3>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Eye contact: Rinse with water for at least 15 minutes.<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Skin contact: Clean with soap and water<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Inhalation: Move to fresh air, medical supervision recommended<\/span><\/span><\/li>\n<\/ul>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Kwaliteitsgarantie<\/span><\/span><\/h2>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Each batch contains:<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">COA with HPLC and MS analysis results<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Batch-specific stability data<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Complete provenance and production documentation<\/span><\/span><\/li>\n<\/ul>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Regelgevend kader<\/span><\/span><\/h2>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Under the Dutch Opium Act<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Only available to accredited research institutions<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Export restrictions apply<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Strictly prohibited for human consumption<\/span><\/span><\/li>\n<\/ul>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Bestelinformatie<\/span><\/span><\/h2>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Minimum order quantity: 1 gram<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Packaging: Anonymous with temperature monitoring<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Delivery time: 2\u20135 working days within the EU<\/span><\/span><\/li>\n<\/ul>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Scientific References<\/span><\/span><\/h2>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Relevant publications on related substances have appeared in:<\/span><\/span><\/p>\n<ul>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Tijdschrift voor Psychofarmacologie<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Neurofarmacologie<\/span><\/span><\/li>\n<li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">ACS Chemical Neuroscience<\/span><\/span><\/li>\n<\/ul>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Disclaimer<\/span><\/span><\/h2>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">This product is intended solely for legally authorized research. Use is permitted only by qualified professionals within applicable legal frameworks. The purchaser is ultimately responsible for compliance.<\/span><\/span><\/p>\n<p><a href=\"http:\/\/google.nl\" target=\"_blank\" rel=\"noopener\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">is <\/span><\/span><\/span><\/span><\/a> <a title=\"1V-LSD 150 MCG Blotters\" href=\"https:\/\/primegloballab.com\/shop\/lysergamides\/1v-lsd-150-mcg-blotters\/\" target=\"_blank\" rel=\"noopener\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1V-LSD 150 MCG Blotters <\/span><\/span><\/span><\/span><\/a><a title=\"6-CL-ADBA\" href=\"https:\/\/primegloballab.com\/shop\/bijna-verboden\/6-cl-adba\/\" target=\"_blank\" rel=\"noopener\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">6-CL-ADBA <\/span><\/span><\/span><\/span><\/a><a title=\"2-CMC 250mg pellets\" href=\"https:\/\/primegloballab.com\/shop\/cathinonen\/2-cmc-kopen\/\" target=\"_blank\" rel=\"noopener\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2-CMC 250mg pellets <\/span><\/span><\/span><\/span><\/a><a title=\"MEAI\" href=\"https:\/\/primegloballab.com\/shop\/overig\/meai\/\" target=\"_blank\" rel=\"noopener\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">MEAI <\/span><\/span><\/span><\/span><\/a><span dir=\"auto\" style=\"vertical-align: inherit;\"><a title=\"2C-EF 2mg Capsules\" href=\"https:\/\/primegloballab.com\/shop\/fenethylamine\/2c-ef-2mg-capsules\/\" target=\"_blank\" rel=\"noopener\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2C-EF 2mg Capsules<\/span><\/span><\/span><\/a><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">\u00a0<\/span><\/span><\/p>","protected":false},"excerpt":{"rendered":"<h2><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">3-FA properties<\/span><\/span><\/span><\/span><\/h2>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Synoniem<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : 3-Fluoroamphetamine <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">CAS-nummer<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : 1716-59-2 <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formule<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : C9H12FN \u2022 HCL <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Molaire massa<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : 189.7 g\/mol <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Zuiverheid<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u226598%<\/span><\/span><\/span><\/span><\/p>","protected":false},"featured_media":28917,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[82],"product_cat":[409,322,333,398],"product_tag":[682,681,680,326],"class_list":{"0":"post-23689","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-research-chemical","7":"product_cat-3-fa","8":"product_cat-bijna-verboden","9":"product_cat-gefluoreerden","10":"product_cat-verkoop","11":"product_tag-3-fluoroamphetamine","12":"product_tag-3fa","13":"product_tag-3fa-kopen","14":"product_tag-nl","16":"first","17":"instock","18":"sale","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/product\/23689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/comments?post=23689"}],"version-history":[{"count":6,"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/product\/23689\/revisions"}],"predecessor-version":[{"id":28054,"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/product\/23689\/revisions\/28054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/media\/28917"}],"wp:attachment":[{"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/media?parent=23689"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/product_brand?post=23689"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/product_cat?post=23689"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/primegloballab.com\/nl\/wp-json\/wp\/v2\/product_tag?post=23689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}