{"id":23807,"date":"2025-04-13T17:40:27","date_gmt":"2025-04-13T17:40:27","guid":{"rendered":"https:\/\/primegloballab.com\/?post_type=product&#038;p=23807"},"modified":"2025-12-09T10:14:33","modified_gmt":"2025-12-09T10:14:33","slug":"4b-marzec","status":"publish","type":"product","link":"https:\/\/primegloballab.com\/pl\/sklep\/aminoreks\/4b-marzec\/","title":{"rendered":"4B-MAR (4-Bromo-4-methylaminorex)"},"content":{"rendered":"<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4B-MAR \/ 4\u2032-Bromo-4-methylaminorex<\/span><\/span><\/strong><\/h2>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4B-MAR<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> is a substance we sell only for research purposes and is therefore not intended for human consumption. 4B-MAR can be researched for up to two years when stored in the correct environment. 2C-E <\/span><\/span><a href=\"https:\/\/primegloballab.com\/shop\/lysergamides\/1v-lsd-150-mcg-blotters\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1V-LSD 150 MCG Blotters<\/span><\/span><\/a><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Because 4F-MAR is for research purposes only and not for consumption, it is important to keep 4B-MAR out of the reach of children and pets. <\/span><\/span><a href=\"https:\/\/primegloballab.com\/shop\/cathinonen\/2-cmc-kopen\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2-CMC 250mg granulki<\/span><\/span><\/a><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">We offer high-quality research chemicals at a fair price. Your order ships within 24 hours every day. Order 4B-MAR safely and quickly through 4-HO-MET Fumarate <\/span><\/span><a href=\"https:\/\/primegloballab.com\/shop\/fenethylamine\/2c-ef-2mg-capsules\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2C-EF 2mg Capsules.<\/span><\/span><\/a><\/p>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4B-MAR \/ <\/span><\/span><b><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4\u2032-bromo-4-methylaminorex<\/span><\/span><\/b><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> w\u0142a\u015bciwo\u015bci<\/span><\/span><\/h2>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Synonym: 4-methyl-5-(4-bromophenyl)-4,5-dihydro-1,3-oxazol-2-amine <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Numer CAS<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : NVT <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formu\u0142a<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : <\/span><\/span><span title=\"W\u0119giel\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">C <\/span><\/span><\/span><sub><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">10 <\/span><\/span><\/sub><span title=\"Wod\u00f3r\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">H <\/span><\/span><\/span><sub><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">11 <\/span><\/span><\/sub><span title=\"Fluorine\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">F <\/span><\/span><\/span><span title=\"Azot\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">N <\/span><\/span><\/span><sub><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2 <\/span><\/span><\/sub><span title=\"Tlen\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">O <\/span><\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Masa molowa<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : <\/span><\/span><span class=\"nowrap\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">195.039<\/span><\/span><\/span><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> g mol <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Czysto\u015b\u0107<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u226598%<\/span><\/span><\/p>\n<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Zwroty wskazuj\u0105ce rodzaj zagro\u017cenia<\/span><\/span><\/h2>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4B-MAR may cause respiratory irritation. <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4B-MAR may cause eye irritation. <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Uwalnianie chemikali\u00f3w badawczych do \u015brodowiska jest zabronione.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4B-MAR IF IN EYES: Rinse eyes gently with water for five minutes. Remove contact lenses, if present and easy to do. 3-MEO-PCP <\/span><\/span><a href=\"https:\/\/primegloballab.com\/shop\/bijna-verboden\/6-cl-adba\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">6-CL-ADBA<\/span><\/span><\/a><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4B-MAR IF ON SKIN: Wash skin with soap and water. <\/span><\/span><a href=\"https:\/\/primegloballab.com\/shop\/overig\/meai\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">MEAI<\/span><\/span><\/a><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">IF INHALED 4B-MAR: Remove victim to fresh air and keep victim in a position comfortable for breathing.3-MEC<\/span><\/span><\/p>","protected":false},"excerpt":{"rendered":"<h2><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4B-MAR \/ <\/span><\/span><b><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">4\u2032-bromo-4-methylaminorex<\/span><\/span><\/b><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> w\u0142a\u015bciwo\u015bci<\/span><\/span><\/h2>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Synonym: 4-methyl-5-(4-bromophenyl)-4,5-dihydro-1,3-oxazol-2-amine <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Numer CAS<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : NVT <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formu\u0142a<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : <\/span><\/span><span title=\"W\u0119giel\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">C <\/span><\/span><\/span><sub><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">10 <\/span><\/span><\/sub><span title=\"Wod\u00f3r\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">H <\/span><\/span><\/span><sub><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">11 <\/span><\/span><\/sub><span title=\"Fluorine\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">F <\/span><\/span><\/span><span title=\"Azot\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">N <\/span><\/span><\/span><sub><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2 <\/span><\/span><\/sub><span title=\"Tlen\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">O <\/span><\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Masa molowa<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : <\/span><\/span><span class=\"nowrap\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">195.039<\/span><\/span><\/span><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> g mol <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Czysto\u015b\u0107<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u226598%<\/span><\/span><\/p>","protected":false},"featured_media":28961,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[82],"product_cat":[552],"product_tag":[648,326],"class_list":{"0":"post-23807","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-research-chemical","7":"product_cat-aminorex","8":"product_tag-4b-mar","9":"product_tag-nl","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/product\/23807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/comments?post=23807"}],"version-history":[{"count":4,"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/product\/23807\/revisions"}],"predecessor-version":[{"id":28451,"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/product\/23807\/revisions\/28451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/media\/28961"}],"wp:attachment":[{"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/media?parent=23807"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/product_brand?post=23807"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/product_cat?post=23807"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/primegloballab.com\/pl\/wp-json\/wp\/v2\/product_tag?post=23807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}