{"id":24007,"date":"2025-04-13T17:40:52","date_gmt":"2025-04-13T17:40:52","guid":{"rendered":"https:\/\/primegloballab.com\/?post_type=product&#038;p=24007"},"modified":"2025-12-09T10:59:31","modified_gmt":"2025-12-09T10:59:31","slug":"%d0%b0mt","status":"publish","type":"product","link":"https:\/\/primegloballab.com\/ru\/%d0%bc%d0%b0%d0%b3%d0%b0%d0%b7%d0%b8%d0%bd\/%d0%b0mt-2\/%d0%b0mt\/","title":{"rendered":"aMT"},"content":{"rendered":"<h1><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">AMT (Alpha-Methyltryptamine) \u2013 Scientific Product Description<\/span><\/span><\/strong><\/h1>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">General Information<\/span><\/span><\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Substance Name:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Alpha-Methyltryptamine (AMT) <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0425\u0438\u043c\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043a\u043b\u0430\u0441\u0441:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Tryptamine derivative <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Status:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Research chemical <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0414\u043e\u0437\u0438\u0440\u043e\u0432\u043a\u0430:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Varies (10-50mg for research purposes) <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0424\u043e\u0440\u043c\u0430:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Powder or pellets (depending on availability)<\/span><\/span><\/p>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0424\u0430\u0440\u043c\u0430\u043a\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0441\u0432\u043e\u0439\u0441\u0442\u0432\u0430<\/span><\/span><\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">AMT is a monoamine alkaloid with a unique mechanism of action that both:<\/span><\/span><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Serotonergic<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0(5-HT\u2082A agonism)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dopaminergic<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0(dopamine reuptake inhibition)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Exhibits noradrenergic<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0effects<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Potential Research Areas<\/span><\/span><\/strong><\/h2>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1. Neuropsychological Examination<\/span><\/span><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Influence on perceptual processing<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Modulation of cognitive flexibility<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Effects on creative thinking<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2. Behavioral Science Studies<\/span><\/span><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Social interaction patterns<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Emotional processing mechanisms<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Motivation and reward systems<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">3. Theoretical Applications<\/span><\/span><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Possible antidepressant effects (preclinical study)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Impact on sleep architecture<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Neuroplastic changes<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dosage &amp; Protocol<\/span><\/span><\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Research dose range:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Low dose:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a010-20mg<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Average dose:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a020-35mg<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">High dose:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a035-50mg<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Time lapse:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Onset of effects: 45-90 minutes<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Peak performance: 3-5 hours<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Total duration: 8-12 hours<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Safety aspects<\/span><\/span><\/strong><\/h2>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Side effects<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Increased body temperature<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Tachycardia<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Mydriasis<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Possible gastrointestinal discomfort<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Contraindications<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u041a\u043e\u043c\u0431\u0438\u043d\u0430\u0446\u0438\u044f \u0441 \u0438\u043d\u0433\u0438\u0431\u0438\u0442\u043e\u0440\u0430\u043c\u0438 \u041c\u0410\u041e<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Cardiovascular diseases<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Psychiatric history<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Laboratory analysis<\/span><\/span><\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0427\u0438\u0441\u0442\u043e\u0442\u0430:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0\u226597% (HPLC) <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0421\u0442\u0430\u0431\u0438\u043b\u044c\u043d\u043e\u0441\u0442\u044c:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Store in a cool, dry place (&lt;25\u00b0C) <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Impurities:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0&lt;0.5% (GC-MS analysis)<\/span><\/span><\/p>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u041f\u0440\u0430\u0432\u043e\u0432\u043e\u0439 \u0441\u0442\u0430\u0442\u0443\u0441<\/span><\/span><\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Netherlands:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Opium Act Schedule I <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Belgium:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Prohibited substance <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">EU:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Under EU NPS legislation<\/span><\/span><\/p>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Research protocols<\/span><\/span><\/strong><\/h2>\n<ol start=\"1\">\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Start low:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a010mg initial test dose<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pharmaceutical monitoring:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Blood pressure and temperature measurement<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Intervals:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Minimum 7 days between experiments<\/span><\/span><\/p>\n<\/li>\n<\/ol>\n<h2><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Important Warnings<\/span><\/span><\/strong><\/h2>\n<p class=\"ds-markdown-paragraph\">\u274c\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">No human consumption <\/span><\/span><\/strong><br \/>\n\u274c\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Do not combine with other psychoactives <\/span><\/span><\/strong><br \/>\n\u274c\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Avoid prolonged or frequent use<\/span><\/span><\/strong><\/p>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">This product is intended solely for in vitro research <\/span><\/span><a href=\"http:\/\/google.nl\" target=\"_blank\" rel=\"noopener\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0438<\/span><\/span><\/a><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> scientific study under controlled laboratory conditions.<\/span><\/span><\/strong><\/p>\n<p><a title=\"1cP-LSD 150 MCG \u0410\u0440\u0442-\u0431\u043b\u043e\u0442\u0442\u0435\u0440\u044b\" href=\"https:\/\/primegloballab.com\/shop\/lysergamides\/1cp-lsd-150-mcg\/\" target=\"_blank\" rel=\"noopener\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1cP-LSD 150 MCG \u0410\u0440\u0442-\u0431\u043b\u043e\u0442\u0442\u0435\u0440\u044b <\/span><\/span><\/a><a title=\"\u041e-\u0414\u0421\u041c\u0422 50 \u043c\u0433 \u0433\u0440\u0430\u043d\u0443\u043b\u044b\" href=\"https:\/\/primegloballab.com\/shop\/pellets\/o-dsmt-50mg-pellets\/\" target=\"_blank\" rel=\"noopener\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u041e-\u0414\u0421\u041c\u0422 50 \u043c\u0433 \u0433\u0440\u0430\u043d\u0443\u043b\u044b <\/span><\/span><\/a><a title=\"\u0411\u043b\u043e\u0442\u0442\u0435\u0440\u044b 1V-LSD 150 MCG\" href=\"https:\/\/primegloballab.com\/shop\/lysergamides\/1v-lsd-150-mcg-blotters\/\" target=\"_blank\" rel=\"noopener\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0411\u043b\u043e\u0442\u0442\u0435\u0440\u044b 1V-LSD 150 MCG <\/span><\/span><\/a><a title=\"6-CL-ADBA\" href=\"https:\/\/primegloballab.com\/shop\/bijna-verboden\/6-cl-adba\/\" target=\"_blank\" rel=\"noopener\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">6-CL-ADBA<\/span><\/span><\/a><\/p>","protected":false},"excerpt":{"rendered":"<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">aMT properties<\/span><\/span><\/h3>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0421\u0438\u043d\u043e\u043d\u0438\u043c:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> alpha-Methyltryptamine <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u041d\u043e\u043c\u0435\u0440 CAS:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 299-26-3 <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0424\u043e\u0440\u043c\u0443\u043b\u0430:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> C11H14N2 <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u041c\u043e\u043b\u044f\u0440\u043d\u0430\u044f \u043c\u0430\u0441\u0441\u0430:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 174.247 g mol\u22121 <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0427\u0438\u0441\u0442\u043e\u0442\u0430:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> &gt;98%<\/span><\/span><\/p>","protected":false},"featured_media":28993,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[82],"product_cat":[404,381],"product_tag":[889,888,891,890,326],"class_list":{"0":"post-24007","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-research-chemical","7":"product_cat-amt","8":"product_cat-tryptamines","9":"product_tag-alpha-methyltryptamine-erowid","10":"product_tag-alpha-methyltryptamine","11":"product_tag-alpha-methyltryptamine-reddit","12":"product_tag-amt-alpha-methyltryptamine","13":"product_tag-nl","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/product\/24007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/comments?post=24007"}],"version-history":[{"count":6,"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/product\/24007\/revisions"}],"predecessor-version":[{"id":28030,"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/product\/24007\/revisions\/28030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/media\/28993"}],"wp:attachment":[{"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/media?parent=24007"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/product_brand?post=24007"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/product_cat?post=24007"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/primegloballab.com\/ru\/wp-json\/wp\/v2\/product_tag?post=24007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}